{"id":1289,"date":"2026-03-03T17:31:44","date_gmt":"2026-03-03T15:31:44","guid":{"rendered":"https:\/\/www.tt-experten.de\/?p=1289"},"modified":"2026-03-03T18:57:18","modified_gmt":"2026-03-03T16:57:18","slug":"andro-belag-hy-q-42-angebotspreis-4250-euro","status":"publish","type":"post","link":"https:\/\/www.tt-experten.de\/index.php\/2026\/03\/03\/andro-belag-hy-q-42-angebotspreis-4250-euro\/","title":{"rendered":"andro Belag HY-Q 42 Angebotspreis 42,50 Euro"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Der HY-Q 42 ist ein moderner Offensivbelag f\u00fcr Spieler, die ihr Topspinspiel mit hoher Rotation und kontrollierter Dynamik gestalten m\u00f6chten. Mit seiner ausgewogenen Abstimmung verbindet er Spinqualit\u00e4t mit verl\u00e4sslicher Beschleunigung.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das leicht klebrige Obergummi erm\u00f6glicht maximalen Effet bei Aufschlag und R\u00fcckschlag und unterst\u00fctzt rotationsreiche Er\u00f6ffnungen mit sicherer Flugkurve. Gleichzeitig sorgt der Tensor-Schwamm im offenen Spiel f\u00fcr die n\u00f6tige Dynamik und ein kontrolliertes Tempo \u2013 ohne an Pr\u00e4zision zu verlieren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ideal f\u00fcr ambitionierte Offensivspieler, die ihr Spiel \u00fcber Spin aufbauen, Sicherheit im Kurzspiel sch\u00e4tzen und im Angriff variabel beschleunigen m\u00f6chten.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der HY-Q 42 ist ein moderner Offensivbelag f\u00fcr Spieler, die ihr Topspinspiel mit hoher Rotation und kontrollierter Dynamik gestalten m\u00f6chten. Mit seiner ausgewogenen Abstimmung verbindet er Spinqualit\u00e4t mit verl\u00e4sslicher Beschleunigung. Das leicht klebrige Obergummi erm\u00f6glicht maximalen Effet bei Aufschlag und R\u00fcckschlag und unterst\u00fctzt rotationsreiche Er\u00f6ffnungen mit sicherer Flugkurve. Gleichzeitig sorgt der Tensor-Schwamm im offenen Spiel [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":1290,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,38,46],"tags":[33,22,20,23],"class_list":["post-1289","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-angebote","category-belaege","category-neuheiten","tag-andro-2","tag-angebote","tag-schoelermicke","tag-tischtennis"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>andro Belag HY-Q 42 Angebotspreis 42,50 Euro - TT-Experten Ro\u00dfkopf &amp; Wei\u00dfbach<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tt-experten.de\/index.php\/2026\/03\/03\/andro-belag-hy-q-42-angebotspreis-4250-euro\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"andro Belag HY-Q 42 Angebotspreis 42,50 Euro - TT-Experten Ro\u00dfkopf &amp; Wei\u00dfbach\" \/>\n<meta property=\"og:description\" content=\"Der HY-Q 42 ist ein moderner Offensivbelag f\u00fcr Spieler, die ihr Topspinspiel mit hoher Rotation und kontrollierter Dynamik gestalten m\u00f6chten. Mit seiner ausgewogenen Abstimmung verbindet er Spinqualit\u00e4t mit verl\u00e4sslicher Beschleunigung. Das leicht klebrige Obergummi erm\u00f6glicht maximalen Effet bei Aufschlag und R\u00fcckschlag und unterst\u00fctzt rotationsreiche Er\u00f6ffnungen mit sicherer Flugkurve. Gleichzeitig sorgt der Tensor-Schwamm im offenen Spiel [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tt-experten.de\/index.php\/2026\/03\/03\/andro-belag-hy-q-42-angebotspreis-4250-euro\/\" \/>\n<meta property=\"og:site_name\" content=\"TT-Experten Ro\u00dfkopf &amp; Wei\u00dfbach\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ttexpertenkoeln\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-03T15:31:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-03T16:57:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tt-experten.de\/wp-content\/uploads\/2026\/03\/andro-Belag-HY-Q42-02-3D-110-021-111-2000x2000px_400x400.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Thomas Ro\u00dfkopf\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thomas Ro\u00dfkopf\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tt-experten.de\\\/index.php\\\/2026\\\/03\\\/03\\\/andro-belag-hy-q-42-angebotspreis-4250-euro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tt-experten.de\\\/index.php\\\/2026\\\/03\\\/03\\\/andro-belag-hy-q-42-angebotspreis-4250-euro\\\/\"},\"author\":{\"name\":\"Thomas Ro\u00dfkopf\",\"@id\":\"https:\\\/\\\/www.tt-experten.de\\\/#\\\/schema\\\/person\\\/ae7eb7a551bdbb6432024bc0f510b54a\"},\"headline\":\"andro Belag HY-Q 42 Angebotspreis 42,50 Euro\",\"datePublished\":\"2026-03-03T15:31:44+00:00\",\"dateModified\":\"2026-03-03T16:57:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tt-experten.de\\\/index.php\\\/2026\\\/03\\\/03\\\/andro-belag-hy-q-42-angebotspreis-4250-euro\\\/\"},\"wordCount\":106,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tt-experten.de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tt-experten.de\\\/index.php\\\/2026\\\/03\\\/03\\\/andro-belag-hy-q-42-angebotspreis-4250-euro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tt-experten.de\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/andro-Belag-HY-Q42-02-3D-110-021-111-2000x2000px_400x400.jpg\",\"keywords\":[\"andro\",\"angebote\",\"sch\u00f6lermicke\",\"tischtennis\"],\"articleSection\":[\"Angebote\",\"Bel\u00e4ge\",\"Neuheiten\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tt-experten.de\\\/index.php\\\/2026\\\/03\\\/03\\\/andro-belag-hy-q-42-angebotspreis-4250-euro\\\/\",\"url\":\"https:\\\/\\\/www.tt-experten.de\\\/index.php\\\/2026\\\/03\\\/03\\\/andro-belag-hy-q-42-angebotspreis-4250-euro\\\/\",\"name\":\"andro Belag HY-Q 42 Angebotspreis 42,50 Euro - TT-Experten Ro\u00dfkopf &amp; Wei\u00dfbach\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tt-experten.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tt-experten.de\\\/index.php\\\/2026\\\/03\\\/03\\\/andro-belag-hy-q-42-angebotspreis-4250-euro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tt-experten.de\\\/index.php\\\/2026\\\/03\\\/03\\\/andro-belag-hy-q-42-angebotspreis-4250-euro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tt-experten.de\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/andro-Belag-HY-Q42-02-3D-110-021-111-2000x2000px_400x400.jpg\",\"datePublished\":\"2026-03-03T15:31:44+00:00\",\"dateModified\":\"2026-03-03T16:57:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tt-experten.de\\\/index.php\\\/2026\\\/03\\\/03\\\/andro-belag-hy-q-42-angebotspreis-4250-euro\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tt-experten.de\\\/index.php\\\/2026\\\/03\\\/03\\\/andro-belag-hy-q-42-angebotspreis-4250-euro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.tt-experten.de\\\/index.php\\\/2026\\\/03\\\/03\\\/andro-belag-hy-q-42-angebotspreis-4250-euro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tt-experten.de\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/andro-Belag-HY-Q42-02-3D-110-021-111-2000x2000px_400x400.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tt-experten.de\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/andro-Belag-HY-Q42-02-3D-110-021-111-2000x2000px_400x400.jpg\",\"width\":400,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tt-experten.de\\\/index.php\\\/2026\\\/03\\\/03\\\/andro-belag-hy-q-42-angebotspreis-4250-euro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tt-experten.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"andro Belag HY-Q 42 Angebotspreis 42,50 Euro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tt-experten.de\\\/#website\",\"url\":\"https:\\\/\\\/www.tt-experten.de\\\/\",\"name\":\"TT-Experten Ro\u00dfkopf & Wei\u00dfbach\",\"description\":\"Tischtennis f\u00fcr Alle\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tt-experten.de\\\/#organization\"},\"alternateName\":\"TT-Experten\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tt-experten.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tt-experten.de\\\/#organization\",\"name\":\"TT-Experten Ro\u00dfkopf & Wei\u00dfbach\",\"url\":\"https:\\\/\\\/www.tt-experten.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.tt-experten.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.tt-experten.de\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cropped-schoeler_micke_partner_blue.png\",\"contentUrl\":\"https:\\\/\\\/www.tt-experten.de\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cropped-schoeler_micke_partner_blue.png\",\"width\":160,\"height\":110,\"caption\":\"TT-Experten Ro\u00dfkopf & Wei\u00dfbach\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tt-experten.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ttexpertenkoeln\",\"https:\\\/\\\/www.instagram.com\\\/tt.experten.rosskopf.weissbach\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tt-experten.de\\\/#\\\/schema\\\/person\\\/ae7eb7a551bdbb6432024bc0f510b54a\",\"name\":\"Thomas Ro\u00dfkopf\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/de2fe3d2d7c9c4ca845e588749bda3b519b8ee2ebc926184fb66e403fde8b376?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/de2fe3d2d7c9c4ca845e588749bda3b519b8ee2ebc926184fb66e403fde8b376?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/de2fe3d2d7c9c4ca845e588749bda3b519b8ee2ebc926184fb66e403fde8b376?s=96&d=mm&r=g\",\"caption\":\"Thomas Ro\u00dfkopf\"},\"url\":\"https:\\\/\\\/www.tt-experten.de\\\/index.php\\\/author\\\/thomas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"andro Belag HY-Q 42 Angebotspreis 42,50 Euro - TT-Experten Ro\u00dfkopf &amp; Wei\u00dfbach","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tt-experten.de\/index.php\/2026\/03\/03\/andro-belag-hy-q-42-angebotspreis-4250-euro\/","og_locale":"de_DE","og_type":"article","og_title":"andro Belag HY-Q 42 Angebotspreis 42,50 Euro - TT-Experten Ro\u00dfkopf &amp; Wei\u00dfbach","og_description":"Der HY-Q 42 ist ein moderner Offensivbelag f\u00fcr Spieler, die ihr Topspinspiel mit hoher Rotation und kontrollierter Dynamik gestalten m\u00f6chten. Mit seiner ausgewogenen Abstimmung verbindet er Spinqualit\u00e4t mit verl\u00e4sslicher Beschleunigung. Das leicht klebrige Obergummi erm\u00f6glicht maximalen Effet bei Aufschlag und R\u00fcckschlag und unterst\u00fctzt rotationsreiche Er\u00f6ffnungen mit sicherer Flugkurve. Gleichzeitig sorgt der Tensor-Schwamm im offenen Spiel [&hellip;]","og_url":"https:\/\/www.tt-experten.de\/index.php\/2026\/03\/03\/andro-belag-hy-q-42-angebotspreis-4250-euro\/","og_site_name":"TT-Experten Ro\u00dfkopf &amp; Wei\u00dfbach","article_publisher":"https:\/\/www.facebook.com\/ttexpertenkoeln","article_published_time":"2026-03-03T15:31:44+00:00","article_modified_time":"2026-03-03T16:57:18+00:00","og_image":[{"width":400,"height":400,"url":"https:\/\/www.tt-experten.de\/wp-content\/uploads\/2026\/03\/andro-Belag-HY-Q42-02-3D-110-021-111-2000x2000px_400x400.jpg","type":"image\/jpeg"}],"author":"Thomas Ro\u00dfkopf","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Thomas Ro\u00dfkopf","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tt-experten.de\/index.php\/2026\/03\/03\/andro-belag-hy-q-42-angebotspreis-4250-euro\/#article","isPartOf":{"@id":"https:\/\/www.tt-experten.de\/index.php\/2026\/03\/03\/andro-belag-hy-q-42-angebotspreis-4250-euro\/"},"author":{"name":"Thomas Ro\u00dfkopf","@id":"https:\/\/www.tt-experten.de\/#\/schema\/person\/ae7eb7a551bdbb6432024bc0f510b54a"},"headline":"andro Belag HY-Q 42 Angebotspreis 42,50 Euro","datePublished":"2026-03-03T15:31:44+00:00","dateModified":"2026-03-03T16:57:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tt-experten.de\/index.php\/2026\/03\/03\/andro-belag-hy-q-42-angebotspreis-4250-euro\/"},"wordCount":106,"publisher":{"@id":"https:\/\/www.tt-experten.de\/#organization"},"image":{"@id":"https:\/\/www.tt-experten.de\/index.php\/2026\/03\/03\/andro-belag-hy-q-42-angebotspreis-4250-euro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tt-experten.de\/wp-content\/uploads\/2026\/03\/andro-Belag-HY-Q42-02-3D-110-021-111-2000x2000px_400x400.jpg","keywords":["andro","angebote","sch\u00f6lermicke","tischtennis"],"articleSection":["Angebote","Bel\u00e4ge","Neuheiten"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.tt-experten.de\/index.php\/2026\/03\/03\/andro-belag-hy-q-42-angebotspreis-4250-euro\/","url":"https:\/\/www.tt-experten.de\/index.php\/2026\/03\/03\/andro-belag-hy-q-42-angebotspreis-4250-euro\/","name":"andro Belag HY-Q 42 Angebotspreis 42,50 Euro - TT-Experten Ro\u00dfkopf &amp; Wei\u00dfbach","isPartOf":{"@id":"https:\/\/www.tt-experten.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tt-experten.de\/index.php\/2026\/03\/03\/andro-belag-hy-q-42-angebotspreis-4250-euro\/#primaryimage"},"image":{"@id":"https:\/\/www.tt-experten.de\/index.php\/2026\/03\/03\/andro-belag-hy-q-42-angebotspreis-4250-euro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tt-experten.de\/wp-content\/uploads\/2026\/03\/andro-Belag-HY-Q42-02-3D-110-021-111-2000x2000px_400x400.jpg","datePublished":"2026-03-03T15:31:44+00:00","dateModified":"2026-03-03T16:57:18+00:00","breadcrumb":{"@id":"https:\/\/www.tt-experten.de\/index.php\/2026\/03\/03\/andro-belag-hy-q-42-angebotspreis-4250-euro\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tt-experten.de\/index.php\/2026\/03\/03\/andro-belag-hy-q-42-angebotspreis-4250-euro\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.tt-experten.de\/index.php\/2026\/03\/03\/andro-belag-hy-q-42-angebotspreis-4250-euro\/#primaryimage","url":"https:\/\/www.tt-experten.de\/wp-content\/uploads\/2026\/03\/andro-Belag-HY-Q42-02-3D-110-021-111-2000x2000px_400x400.jpg","contentUrl":"https:\/\/www.tt-experten.de\/wp-content\/uploads\/2026\/03\/andro-Belag-HY-Q42-02-3D-110-021-111-2000x2000px_400x400.jpg","width":400,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.tt-experten.de\/index.php\/2026\/03\/03\/andro-belag-hy-q-42-angebotspreis-4250-euro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tt-experten.de\/"},{"@type":"ListItem","position":2,"name":"andro Belag HY-Q 42 Angebotspreis 42,50 Euro"}]},{"@type":"WebSite","@id":"https:\/\/www.tt-experten.de\/#website","url":"https:\/\/www.tt-experten.de\/","name":"TT-Experten Ro\u00dfkopf & Wei\u00dfbach","description":"Tischtennis f\u00fcr Alle","publisher":{"@id":"https:\/\/www.tt-experten.de\/#organization"},"alternateName":"TT-Experten","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tt-experten.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.tt-experten.de\/#organization","name":"TT-Experten Ro\u00dfkopf & Wei\u00dfbach","url":"https:\/\/www.tt-experten.de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.tt-experten.de\/#\/schema\/logo\/image\/","url":"https:\/\/www.tt-experten.de\/wp-content\/uploads\/2024\/03\/cropped-schoeler_micke_partner_blue.png","contentUrl":"https:\/\/www.tt-experten.de\/wp-content\/uploads\/2024\/03\/cropped-schoeler_micke_partner_blue.png","width":160,"height":110,"caption":"TT-Experten Ro\u00dfkopf & Wei\u00dfbach"},"image":{"@id":"https:\/\/www.tt-experten.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ttexpertenkoeln","https:\/\/www.instagram.com\/tt.experten.rosskopf.weissbach\/"]},{"@type":"Person","@id":"https:\/\/www.tt-experten.de\/#\/schema\/person\/ae7eb7a551bdbb6432024bc0f510b54a","name":"Thomas Ro\u00dfkopf","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/de2fe3d2d7c9c4ca845e588749bda3b519b8ee2ebc926184fb66e403fde8b376?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/de2fe3d2d7c9c4ca845e588749bda3b519b8ee2ebc926184fb66e403fde8b376?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/de2fe3d2d7c9c4ca845e588749bda3b519b8ee2ebc926184fb66e403fde8b376?s=96&d=mm&r=g","caption":"Thomas Ro\u00dfkopf"},"url":"https:\/\/www.tt-experten.de\/index.php\/author\/thomas\/"}]}},"_links":{"self":[{"href":"https:\/\/www.tt-experten.de\/index.php\/wp-json\/wp\/v2\/posts\/1289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tt-experten.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tt-experten.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tt-experten.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tt-experten.de\/index.php\/wp-json\/wp\/v2\/comments?post=1289"}],"version-history":[{"count":1,"href":"https:\/\/www.tt-experten.de\/index.php\/wp-json\/wp\/v2\/posts\/1289\/revisions"}],"predecessor-version":[{"id":1291,"href":"https:\/\/www.tt-experten.de\/index.php\/wp-json\/wp\/v2\/posts\/1289\/revisions\/1291"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tt-experten.de\/index.php\/wp-json\/wp\/v2\/media\/1290"}],"wp:attachment":[{"href":"https:\/\/www.tt-experten.de\/index.php\/wp-json\/wp\/v2\/media?parent=1289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tt-experten.de\/index.php\/wp-json\/wp\/v2\/categories?post=1289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tt-experten.de\/index.php\/wp-json\/wp\/v2\/tags?post=1289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}